{"id":2596,"date":"2021-05-26T20:36:24","date_gmt":"2021-05-26T18:36:24","guid":{"rendered":"http:\/\/marchedudimanche.be\/wordpress\/?p=2596"},"modified":"2021-05-26T21:10:21","modified_gmt":"2021-05-26T19:10:21","slug":"elouges-historique","status":"publish","type":"post","link":"http:\/\/marchedudimanche.be\/wordpress\/2021\/05\/26\/elouges-historique\/","title":{"rendered":"Elouges &#8211; Historique"},"content":{"rendered":"\n<p>Elouges est un\nvillage de l\u2019entit\u00e9 de Dour.<\/p>\n\n\n\n<p>Des recherches arch\u00e9ologiques donne \u00e0 penser que la localit\u00e9 est une des plus anciennes du Borinage. Elle \u00e9tait jadis constitu\u00e9e de deux noyaux villageois&nbsp;: Elouges et Monceau, poss\u00e9dant chacun&nbsp; leur \u00e9glise.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"290\" height=\"178\" src=\"http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2020\/10\/image-7.png\" alt=\"\" class=\"wp-image-1783\"\/><figcaption>La place d&rsquo;Elouges hier<br><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"230\" height=\"172\" src=\"http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2020\/10\/image-8.png\" alt=\"\" class=\"wp-image-1784\"\/><figcaption>La place d&rsquo;Elouges aujourd&rsquo;hui<\/figcaption><\/figure>\n\n\n\n<p>Depuis la fusion des communes de 1977, le village d\u2019Elouges fait partie, avec les localit\u00e9s de Blaugies, Dour et Wih\u00e9ries, de l\u2019entit\u00e9 de Dour.<\/p>\n\n\n\n<p><strong>Exploitation industrielle:<\/strong><\/p>\n\n\n\n<p>Elouges a connu la prosp\u00e9rit\u00e9 \u00e0 l\u2019\u00e9poque des charbonnages avec l\u2019exploitation des concessions  de la Grande Veine du Bois d\u2019Epinois, de Longterne-Ferrand et de Belle-Vue, par la suite int\u00e9gr\u00e9s dans la S.A. de l&rsquo;Ouest de Mons. <\/p>\n\n\n\n<p>De la chaux a \u00e9galement \u00e9t\u00e9 extraite d\u2019une carri\u00e8re \u00e0 ciel ouvert jusque dans les ann\u00e9es 1920.<\/p>\n\n\n\n<p><strong>Le tramway:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"512\" height=\"326\" src=\"http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2021\/05\/image-13.png\" alt=\"\" class=\"wp-image-2602\" srcset=\"http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2021\/05\/image-13.png 512w, http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2021\/05\/image-13-300x191.png 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><figcaption>Le tram 6 \u00e0 son terminus, place d&rsquo;Elouges<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elouges est un village de l\u2019entit\u00e9 de Dour. Des recherches arch\u00e9ologiques donne \u00e0 penser que la localit\u00e9 est une des plus anciennes du Borinage. Elle \u00e9tait jadis constitu\u00e9e de deux noyaux villageois&nbsp;: Elouges et Monceau, poss\u00e9dant chacun&nbsp; leur \u00e9glise. Depuis la fusion des communes de 1977, le village d\u2019Elouges fait partie, avec les localit\u00e9s de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,20],"tags":[],"class_list":["post-2596","post","type-post","status-publish","format-standard","hentry","category-elouges","category-trams"],"_links":{"self":[{"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/posts\/2596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/comments?post=2596"}],"version-history":[{"count":3,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/posts\/2596\/revisions"}],"predecessor-version":[{"id":2603,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/posts\/2596\/revisions\/2603"}],"wp:attachment":[{"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/media?parent=2596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/categories?post=2596"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/tags?post=2596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}