{"id":3106,"date":"2021-09-27T09:38:29","date_gmt":"2021-09-27T07:38:29","guid":{"rendered":"http:\/\/marchedudimanche.be\/wordpress\/?p=3106"},"modified":"2021-09-27T09:38:30","modified_gmt":"2021-09-27T07:38:30","slug":"boussu-les-vergers","status":"publish","type":"post","link":"http:\/\/marchedudimanche.be\/wordpress\/2021\/09\/27\/boussu-les-vergers\/","title":{"rendered":"Boussu &#8211; Les vergers"},"content":{"rendered":"\n<p>Les vergers de Boussu ont \u00e9t\u00e9 am\u00e9nag\u00e9s sur le site occup\u00e9 jadis par le puits n\u00b0 5, dit Sentinelle, de la S.A. des Charbonnages unis de l\u2019Ouest de Mons. Mis en exploitation le 4 ao\u00fbt 1827 et ferm\u00e9 le 25 f\u00e9vrier 1961.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"454\" height=\"286\" src=\"http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2021\/09\/image-6.png\" alt=\"\" class=\"wp-image-3107\" srcset=\"http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2021\/09\/image-6.png 454w, http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2021\/09\/image-6-300x189.png 300w\" sizes=\"(max-width: 454px) 100vw, 454px\" \/><figcaption>Boussu-bois &#8211; Puits Sentinelle<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"605\" height=\"454\" src=\"http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2021\/09\/image-7.png\" alt=\"\" class=\"wp-image-3108\" srcset=\"http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2021\/09\/image-7.png 605w, http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2021\/09\/image-7-300x225.png 300w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/><figcaption>Boussu &#8211; Les vergers<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Les vergers de Boussu ont \u00e9t\u00e9 am\u00e9nag\u00e9s sur le site occup\u00e9 jadis par le puits n\u00b0 5, dit Sentinelle, de la S.A. des Charbonnages unis de l\u2019Ouest de Mons. Mis en exploitation le 4 ao\u00fbt 1827 et ferm\u00e9 le 25 f\u00e9vrier 1961.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66,18],"tags":[],"class_list":["post-3106","post","type-post","status-publish","format-standard","hentry","category-boussu","category-forets-et-bois"],"_links":{"self":[{"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/posts\/3106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/comments?post=3106"}],"version-history":[{"count":1,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/posts\/3106\/revisions"}],"predecessor-version":[{"id":3109,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/posts\/3106\/revisions\/3109"}],"wp:attachment":[{"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/media?parent=3106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/categories?post=3106"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/tags?post=3106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}