{"id":3682,"date":"2022-03-28T09:19:35","date_gmt":"2022-03-28T07:19:35","guid":{"rendered":"http:\/\/marchedudimanche.be\/wordpress\/?p=3682"},"modified":"2022-03-28T09:20:54","modified_gmt":"2022-03-28T07:20:54","slug":"givry","status":"publish","type":"post","link":"http:\/\/marchedudimanche.be\/wordpress\/2022\/03\/28\/givry\/","title":{"rendered":"Givry"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"669\" height=\"870\" src=\"http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2022\/03\/image-5.png\" alt=\"\" class=\"wp-image-3683\" srcset=\"http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2022\/03\/image-5.png 669w, http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2022\/03\/image-5-231x300.png 231w\" sizes=\"(max-width: 669px) 100vw, 669px\" \/><figcaption>Givry &#8211; La place de l&rsquo;\u00e9glise<\/figcaption><\/figure>\n\n\n\n<p>Le village de\nGivry est situ\u00e9 le long de la fronti\u00e8re franco-belge au point de rencontre\nentre la rivi\u00e8re la Trouille et l\u2019ancienne chauss\u00e9e romaine allant de Bavay \u00e0\nUtrecht.<\/p>\n\n\n\n<p>C\u2019est une localit\u00e9 rurale et r\u00e9sidentielle qui s\u2019\u00e9tend sur 1421 ha. La Trouille prend sa source \u00e0 Grand-Reng (entit\u00e9 d\u2019Erquelinnes). Elle s\u2019\u00e9coule d\u2019abord vers la France (Villers-Sire-Nicole) avant de revenir en Belgique \u00e0 Rouveroy. Elle traverse ensuite Givry, o\u00f9 elle provoque de fr\u00e9quentes inondations,\u00a0 et se dirige vers Mons. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"945\" height=\"945\" src=\"http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2022\/03\/image-6.png\" alt=\"\" class=\"wp-image-3685\" srcset=\"http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2022\/03\/image-6.png 945w, http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2022\/03\/image-6-300x300.png 300w, http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2022\/03\/image-6-150x150.png 150w, http:\/\/marchedudimanche.be\/wordpress\/wp-content\/uploads\/2022\/03\/image-6-768x768.png 768w\" sizes=\"(max-width: 945px) 100vw, 945px\" \/><figcaption>La \u00ab\u00a0trouille\u00a0\u00bb \u00e0 Givry<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Le village de Givry est situ\u00e9 le long de la fronti\u00e8re franco-belge au point de rencontre entre la rivi\u00e8re la Trouille et l\u2019ancienne chauss\u00e9e romaine allant de Bavay \u00e0 Utrecht. C\u2019est une localit\u00e9 rurale et r\u00e9sidentielle qui s\u2019\u00e9tend sur 1421 ha. La Trouille prend sa source \u00e0 Grand-Reng (entit\u00e9 d\u2019Erquelinnes). Elle s\u2019\u00e9coule d\u2019abord vers la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[],"class_list":["post-3682","post","type-post","status-publish","format-standard","hentry","category-givry"],"_links":{"self":[{"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/posts\/3682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/comments?post=3682"}],"version-history":[{"count":2,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/posts\/3682\/revisions"}],"predecessor-version":[{"id":3686,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/posts\/3682\/revisions\/3686"}],"wp:attachment":[{"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/media?parent=3682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/categories?post=3682"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/marchedudimanche.be\/wordpress\/wp-json\/wp\/v2\/tags?post=3682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}